{"id":18266,"date":"2022-08-16T20:30:00","date_gmt":"2022-08-16T11:30:00","guid":{"rendered":"https:\/\/www.kox-radio.jp\/takeoff7\/?p=18266"},"modified":"2023-01-10T14:26:27","modified_gmt":"2023-01-10T05:26:27","slug":"take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d","status":"publish","type":"post","link":"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/","title":{"rendered":"TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d"},"content":{"rendered":"\n\n\n<p><strong>\u3010\u516c\u6f14\u540d\u3011<\/strong><strong><span style=\"font-size: 10pt;\"><br>TAKE OFF7 presents IDOL SEVEN<br>\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d<br><\/span><\/strong><strong>\u3010\u51fa\u6f14\u3011<\/strong><br><strong><span style=\"font-size: 10pt;\">\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\uff0fCUPIDOLIC<\/span><span style=\"font-size: 12pt;\"><br><\/span>\u3010\u958b\u5834\uff0f\u958b\u6f14\u3011<\/strong><br><strong><span style=\"font-size: 10pt;\">19:30<\/span>\uff0f<span style=\"font-size: 10pt;\">20:00<\/span><\/strong><br><strong>\u3010\u524d\u58f2\uff0f\u5f53\u65e5\u3011<\/strong><br><strong><span style=\"font-size: 10pt;\">\u00a52,000 \uff0f \u00a52,500<\/span><span style=\"font-size: 10pt;\">(1\u30c9\u30ea\u30f3\u30af\u4ee3\u00a5600\u5225)<br><\/span><\/strong><strong>\u3010\u914d\u4fe1\u3011<br><span style=\"font-size: 10pt;\">\u00a51,000<\/span><\/strong><\/p>\n\n\n\n<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-18237\" src=\"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101-300x200.png\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101-300x200.png 300w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101-1024x683.png 1024w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101-768x512.png 768w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101-1536x1024.png 1536w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101-2048x1365.png 2048w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101-600x400.png 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-18240\" src=\"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/b154ff3e6fe5998b1d6f323c1818eb72-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/b154ff3e6fe5998b1d6f323c1818eb72-300x200.jpg 300w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/b154ff3e6fe5998b1d6f323c1818eb72-1024x683.jpg 1024w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/b154ff3e6fe5998b1d6f323c1818eb72-768x512.jpg 768w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/b154ff3e6fe5998b1d6f323c1818eb72-1536x1024.jpg 1536w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/b154ff3e6fe5998b1d6f323c1818eb72-2048x1365.jpg 2048w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/b154ff3e6fe5998b1d6f323c1818eb72-600x400.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>\u00a0<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-17088\" src=\"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/01\/d8de02765a08e465f07e56f61eb8dba9-e1660962308535-300x119.png\" alt=\"\" width=\"300\" height=\"119\" srcset=\"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/01\/d8de02765a08e465f07e56f61eb8dba9-e1660962308535-300x119.png 300w, https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/01\/d8de02765a08e465f07e56f61eb8dba9-e1660962308535.png 318w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>\u3010\u4e3b\u50ac\u3011SHIBUYA TAKEOFF7 (\u682a\u5f0f\u4f1a\u793e\u30b1\u30a4\u30aa\u30fc\u30a8\u30c3\u30af\u30b9\u30e9\u30b8\u30aa\uff09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u3010\u516c\u6f14\u540d\u3011TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d\u3010\u51fa\u6f14\u3011\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\uff0fCUPIDOLIC\u3010\u958b\u5834\uff0f\u958b\u6f14\u301119:30\uff0f20:00\u3010\u524d\u58f2\uff0f\u5f53\u65e5\u3011\u00a52,000 \uff0f \u00a52, &#8230; <a href=\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/\">Continue &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d - SHIBUYA TAKE OFF 7<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14vol-3\u300d\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d - SHIBUYA TAKE OFF 7\" \/>\n<meta property=\"og:description\" content=\"\u3010\u516c\u6f14\u540d\u3011TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d\u3010\u51fa\u6f14\u3011\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\uff0fCUPIDOLIC\u3010\u958b\u5834\uff0f\u958b\u6f14\u301119:30\uff0f20:00\u3010\u524d\u58f2\uff0f\u5f53\u65e5\u3011\u00a52,000 \uff0f \u00a52, ... Continue &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14vol-3\u300d\/\" \/>\n<meta property=\"og:site_name\" content=\"SHIBUYA TAKE OFF 7\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-16T11:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-10T05:26:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101-300x200.png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"TAKEOFF7\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/#website\",\"url\":\"https:\/\/www.kox-radio.jp\/takeoff7\/\",\"name\":\"SHIBUYA TAKE OFF 7\",\"description\":\"SHIBUYA TAKE OFF 7\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kox-radio.jp\/takeoff7\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#primaryimage\",\"url\":\"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101.png\",\"contentUrl\":\"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101.png\",\"width\":3000,\"height\":2000},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#webpage\",\"url\":\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/\",\"name\":\"TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d - SHIBUYA TAKE OFF 7\",\"isPartOf\":{\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#primaryimage\"},\"datePublished\":\"2022-08-16T11:30:00+00:00\",\"dateModified\":\"2023-01-10T05:26:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/#\/schema\/person\/59ec01ce9edac99c94ca6c36c5dd8cc8\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kox-radio.jp\/takeoff7\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/#\/schema\/person\/59ec01ce9edac99c94ca6c36c5dd8cc8\",\"name\":\"TAKEOFF7\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.kox-radio.jp\/takeoff7\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/de03cb5de21aed95079dd9b755a89fd4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/de03cb5de21aed95079dd9b755a89fd4?s=96&d=mm&r=g\",\"caption\":\"TAKEOFF7\"},\"url\":\"https:\/\/www.kox-radio.jp\/takeoff7\/author\/takeoff7\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d - SHIBUYA TAKE OFF 7","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14vol-3\u300d\/","og_locale":"ja_JP","og_type":"article","og_title":"TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d - SHIBUYA TAKE OFF 7","og_description":"\u3010\u516c\u6f14\u540d\u3011TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d\u3010\u51fa\u6f14\u3011\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\uff0fCUPIDOLIC\u3010\u958b\u5834\uff0f\u958b\u6f14\u301119:30\uff0f20:00\u3010\u524d\u58f2\uff0f\u5f53\u65e5\u3011\u00a52,000 \uff0f \u00a52, ... Continue &rarr;","og_url":"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14vol-3\u300d\/","og_site_name":"SHIBUYA TAKE OFF 7","article_published_time":"2022-08-16T11:30:00+00:00","article_modified_time":"2023-01-10T05:26:27+00:00","og_image":[{"url":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101-300x200.png"}],"twitter_card":"summary","twitter_misc":{"\u57f7\u7b46\u8005":"TAKEOFF7","\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.kox-radio.jp\/takeoff7\/#website","url":"https:\/\/www.kox-radio.jp\/takeoff7\/","name":"SHIBUYA TAKE OFF 7","description":"SHIBUYA TAKE OFF 7","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kox-radio.jp\/takeoff7\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#primaryimage","url":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101.png","contentUrl":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-content\/uploads\/2022\/05\/stay_blue_a_sha_2022_1101.png","width":3000,"height":2000},{"@type":"WebPage","@id":"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#webpage","url":"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/","name":"TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d - SHIBUYA TAKE OFF 7","isPartOf":{"@id":"https:\/\/www.kox-radio.jp\/takeoff7\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#primaryimage"},"datePublished":"2022-08-16T11:30:00+00:00","dateModified":"2023-01-10T05:26:27+00:00","author":{"@id":"https:\/\/www.kox-radio.jp\/takeoff7\/#\/schema\/person\/59ec01ce9edac99c94ca6c36c5dd8cc8"},"breadcrumb":{"@id":"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kox-radio.jp\/takeoff7\/2022\/08\/16\/take-off7-presents-idol-seven%e3%80%8c%e3%83%96%e3%83%ab%e3%83%bc%e3%81%aa%e3%81%be%e3%81%be%e3%81%a7%e5%ae%9a%e6%9c%9f%e5%85%ac%e6%bc%94vol-3%e3%80%8d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kox-radio.jp\/takeoff7\/"},{"@type":"ListItem","position":2,"name":"TAKE OFF7 presents IDOL SEVEN\u300c\u30d6\u30eb\u30fc\u306a\u307e\u307e\u3067\u5b9a\u671f\u516c\u6f14Vol.3\u300d"}]},{"@type":"Person","@id":"https:\/\/www.kox-radio.jp\/takeoff7\/#\/schema\/person\/59ec01ce9edac99c94ca6c36c5dd8cc8","name":"TAKEOFF7","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.kox-radio.jp\/takeoff7\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/de03cb5de21aed95079dd9b755a89fd4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de03cb5de21aed95079dd9b755a89fd4?s=96&d=mm&r=g","caption":"TAKEOFF7"},"url":"https:\/\/www.kox-radio.jp\/takeoff7\/author\/takeoff7\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/posts\/18266"}],"collection":[{"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/comments?post=18266"}],"version-history":[{"count":3,"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/posts\/18266\/revisions"}],"predecessor-version":[{"id":18298,"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/posts\/18266\/revisions\/18298"}],"wp:attachment":[{"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/media?parent=18266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/categories?post=18266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kox-radio.jp\/takeoff7\/wp-json\/wp\/v2\/tags?post=18266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}